{"id":564,"date":"2025-10-31T10:26:31","date_gmt":"2025-10-31T09:26:31","guid":{"rendered":"https:\/\/www.thetraka.com\/prensa\/"},"modified":"2026-07-14T09:47:36","modified_gmt":"2026-07-14T07:47:36","slug":"prensa","status":"publish","type":"page","link":"https:\/\/www.thetraka.com\/es\/prensa\/","title":{"rendered":"PRENSA"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(0,0,0,0.66)\u00bb background_image=\u00bbhttps:\/\/www.thetraka.com\/wp-content\/uploads\/2025\/10\/press-the-traka-001.jpg\u00bb background_blend=\u00bboverlay\u00bb custom_padding=\u00bb295px||100px||false|false\u00bb custom_padding_tablet=\u00bb310px||110px||false|false\u00bb custom_padding_phone=\u00bb165px||45px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px||20px||true|false\u00bb custom_padding_tablet=\u00bb22px||22px||true|false\u00bb custom_padding_phone=\u00bb23px||25px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb62px\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb75px\u00bb header_letter_spacing=\u00bb2px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_font_size_tablet=\u00bb60px\u00bb header_font_size_phone=\u00bb42px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_text_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>PRENSA<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb4&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; custom_margin=\u00bb||2px||false|false\u00bb custom_margin_tablet=\u00bb||4px||false|false\u00bb custom_margin_phone=\u00bb||3px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>PRENSA<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb||20px|||\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Aqu\u00ed encontrar\u00e1s todo el contenido de prensa, comunicados y dosieres de \u00abThe Traka\u00bb. Este material es propiedad de Klassmark y <strong>solo puede utilizarse para promocionar el evento, respetando los t\u00e9rminos de derechos de autor que se indican a continuaci\u00f3n.<\/strong> <\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb17px\u00bb text_letter_spacing=\u00bb3px\u00bb text_line_height=\u00bb1.2em\u00bb background_color=\u00bb#000000&#8243; text_orientation=\u00bbcenter\u00bb width=\u00bb220px\u00bb width_tablet=\u00bb231px\u00bb width_phone=\u00bb261px\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb12px||12px||true|false\u00bb link_option_url=\u00bbhttps:\/\/drive.google.com\/drive\/folders\/1dEnpezuVTJnLREULpailK6KZ3IHZ1wSL?usp=sharing\u00bb link_option_url_new_window=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb background__hover_enabled=\u00bbon|hover\u00bb background_color__hover=\u00bb#282828&#8243; background_enable_color__hover=\u00bbon\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb101%|101%\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>KIT DE PRENSA \u00bb<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; custom_margin=\u00bb||2px||false|false\u00bb custom_margin_tablet=\u00bb||4px||false|false\u00bb custom_margin_phone=\u00bb||3px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>ACREDITACI\u00d3N DE PRENSA<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.4em\u00bb width=\u00bb90%\u00bb width_tablet=\u00bb99%\u00bb width_phone=\u00bb100%\u00bb width_last_edited=\u00bbon|phone\u00bb custom_margin=\u00bb||20px|||\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Si trabajas para un medio de comunicaci\u00f3n, una marca o un atleta durante \u00abThe Traka\u00bb, por favor, <strong>rellena el formulario de acreditaci\u00f3n.<\/strong> El equipo de Klassmark revisar\u00e1 y confirmar\u00e1 tu solicitud por correo electr\u00f3nico.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb17px\u00bb text_letter_spacing=\u00bb3px\u00bb text_line_height=\u00bb1.2em\u00bb background_color=\u00bb#000000&#8243; text_orientation=\u00bbcenter\u00bb width=\u00bb220px\u00bb width_tablet=\u00bb231px\u00bb width_phone=\u00bb261px\u00bb width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb12px||12px||true|false\u00bb link_option_url_new_window=\u00bbon\u00bb hover_enabled=\u00bb0&#8243; text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb background__hover_enabled=\u00bbon|hover\u00bb background_color__hover=\u00bb#282828&#8243; background_enable_color__hover=\u00bbon\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb101%|101%\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>INSCR\u00cdBETE \u00bb<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb1300px\u00bb custom_margin=\u00bb50px|auto||auto|false|false\u00bb custom_margin_tablet=\u00bb50px||||false|false\u00bb custom_margin_phone=\u00bb40px||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb70px||||false|false\u00bb border_width_top=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1em\u00bb custom_margin=\u00bb||2px||false|false\u00bb custom_margin_tablet=\u00bb||4px||false|false\u00bb custom_margin_phone=\u00bb||3px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb17px\u00bb text_font_size_phone=\u00bb16px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>DERECHOS DE AUTOR EN REDES SOCIALES<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb20px||20px||false|false\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Las im\u00e1genes de The Traka compartidas en Instagram, YouTube u otras plataformas deben incluir la atribuci\u00f3n completa de los derechos de autor en el pie de foto de la publicaci\u00f3n (no solo como una etiqueta):<\/p>\n<p><strong>@thetraka | @nombre del fot\u00f3grafo<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1em\u00bb custom_margin=\u00bb||2px||false|false\u00bb custom_margin_tablet=\u00bb||4px||false|false\u00bb custom_margin_phone=\u00bb||3px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb17px\u00bb text_font_size_phone=\u00bb16px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>USO EN PRENSA E IMPRESI\u00d3N<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb20px||20px||false|false\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El uso de im\u00e1genes debe incluir los derechos de autor en el siguiente formato:<\/p>\n<p><strong>\u00a9 the traka \u2013 Nombre del fot\u00f3grafo<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1em\u00bb custom_margin=\u00bb||2px||false|false\u00bb custom_margin_tablet=\u00bb||4px||false|false\u00bb custom_margin_phone=\u00bb||3px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb17px\u00bb text_font_size_phone=\u00bb16px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>USO COMERCIAL<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb20px||20px||false|false\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]Todas las im\u00e1genes tomadas en The Traka son propiedad exclusiva del evento.<br \/>\nCualquier uso comercial debe ser negociado y aprobado directamente con Klassmark. Los fot\u00f3grafos no est\u00e1n autorizados a licenciar im\u00e1genes para fines comerciales<br \/>\nde forma independiente.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1em\u00bb custom_margin=\u00bb||2px||false|false\u00bb custom_margin_tablet=\u00bb||4px||false|false\u00bb custom_margin_phone=\u00bb||3px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb17px\u00bb text_font_size_phone=\u00bb16px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<strong>ACREDITACI\u00d3N DE FOT\u00d3GRAFOS<\/strong>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb text_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb20px||20px||false|false\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb15px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]Al aceptar las credenciales de los medios, los fot\u00f3grafos ceden todos los derechos comerciales a Klassmark. La organizaci\u00f3n puede utilizar todas las im\u00e1genes para su propio uso promocional o<br \/>\neditorial sin compensaci\u00f3n adicional.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRENSAPRENSAAqu\u00ed encontrar\u00e1s todo el contenido de prensa, comunicados y dosieres de \u00abThe Traka\u00bb. Este material es propiedad de Klassmark y solo puede utilizarse para promocionar el evento, respetando los t\u00e9rminos de derechos de autor que se indican a continuaci\u00f3n. KIT DE PRENSA \u00bbACREDITACI\u00d3N DE PRENSASi trabajas para un medio de comunicaci\u00f3n, una marca o un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":550,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-564","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages\/564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/comments?post=564"}],"version-history":[{"count":35,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages\/564\/revisions"}],"predecessor-version":[{"id":7264,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages\/564\/revisions\/7264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/media\/550"}],"wp:attachment":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/media?parent=564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}