{"id":726,"date":"2025-10-29T20:56:46","date_gmt":"2025-10-29T19:56:46","guid":{"rendered":"https:\/\/www.thetraka.com\/ubicaciones\/"},"modified":"2026-07-13T13:37:51","modified_gmt":"2026-07-13T11:37:51","slug":"ubicaciones","status":"publish","type":"page","link":"https:\/\/www.thetraka.com\/es\/ubicaciones\/","title":{"rendered":"UBICACIONES"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(0,0,0,0.66)\u00bb background_image=\u00bbhttps:\/\/www.thetraka.com\/wp-content\/uploads\/2025\/10\/the-traka-002.jpg\u00bb background_position=\u00bbtop_center\u00bb background_blend=\u00bboverlay\u00bb custom_padding=\u00bb290px||130px||false|false\u00bb custom_padding_tablet=\u00bb306px||107px||false|false\u00bb custom_padding_phone=\u00bb230px||55px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px||20px||true|false\u00bb custom_padding_tablet=\u00bb22px||22px||true|false\u00bb custom_padding_phone=\u00bb23px||25px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb62px\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb75px\u00bb header_letter_spacing=\u00bb2px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_font_size_tablet=\u00bb60px\u00bb header_font_size_phone=\u00bb42px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_text_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>UBICACIONES<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; background_image=\u00bbhttps:\/\/www.thetraka.com\/wp-content\/uploads\/2025\/10\/bg-the-traka-scaled.png\u00bb parallax=\u00bbon\u00bb parallax_method=\u00bboff\u00bb custom_padding=\u00bb0px||80px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb698px\u00bb max_width_tablet=\u00bb90%\u00bb max_width_phone=\u00bb100%\u00bb max_width_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_tabs active_tab_background_color=\u00bb#000000&#8243; active_tab_text_color=\u00bb#FFFFFF\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb tab_text_color=\u00bb#000000&#8243; body_font_size=\u00bb16px\u00bb tab_font_size=\u00bb16px\u00bb tab_line_height=\u00bb2em\u00bb body_link_font=\u00bb||||on||||\u00bb custom_margin=\u00bb-50px||||false|false\u00bb custom_margin_tablet=\u00bb-40px||||false|false\u00bb custom_margin_phone=\u00bb-35px||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; body_font_size_tablet=\u00bb15px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb tab_font_size_tablet=\u00bb15px\u00bb tab_font_size_phone=\u00bb14px\u00bb tab_font_size_last_edited=\u00bbon|phone\u00bb tab_line_height_tablet=\u00bb1.5em\u00bb tab_line_height_phone=\u00bb1.4em\u00bb tab_line_height_last_edited=\u00bbon|phone\u00bb custom_css_free_form=\u00bb\/* Vista m\u00f2bil: 3 files amb 2 columnes *\/||@media (max-width: 767px) {||  .custom-tabs-grid .et_pb_tabs_controls {||    display: flex;||    flex-wrap: wrap;||    justify-content: space-between;||    gap: 10px;||  }||||  .custom-tabs-grid .et_pb_tabs_controls li {||    width: 48%;||    margin: 0;||  }||}||\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_tab title=\u00bbGENERAL\u00bb title_last_edited=\u00bboff|phone\u00bb content_tablet=\u00bb<\/p>\n<p data-start=%22136%22 data-end=%22157%22 style=%22text-align: left;%22><strong data-start=%22136%22 data-end=%22157%22>BIENVENIDO A GIRONA<\/strong><\/p>\n<p data-start=%22159%22 data-end=%22279%22 style=%22text-align: left;%22>En The Traka, solo tienes que pedalear. Todo tiene lugar en una misma zona, a solo cinco minutos del casco antiguo de Girona. <\/p>\n<p data-start=%22281%22 data-end=%22376%22 style=%22text-align: left;%22>\u00bfQuieres m\u00e1s? Descubre la historia, la gente, la gastronom\u00eda y las calles de la ciudad, a solo 100 km de Barcelona. <\/p>\n<p data-start=%22378%22 data-end=%22441%22 style=%22text-align: left;%22>El d\u00eda de la carrera, sal directamente desde tu casa, hotel o apartamento.<\/p>\n<p data-start=%22443%22 data-end=%22529%22 style=%22text-align: left;%22>Del <strong data-start=%22448%22 data-end=%22469%22>29 de abril al 3 de mayo<\/strong>, descubre por qu\u00e9 Girona es mucho m\u00e1s que la capital del ciclismo.<\/p>\n<p data-start=%22584%22 data-end=%22673%22 style=%22text-align: left;%22>\n<div class=%22text-lead%22>\n<p style=%22text-align: left;%22>\n<div class=%22uncode_text_column%22 style=%22text-align: left;%22>\n<h6 class=%22avia-image-overlay-wrap%22><span style=%22color: #ff9900;%22>EN COCHE<\/span><\/h6>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<ul>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Barcelona\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.690018,2.2086774,72182m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12a49816718e30e5:0x44b0fb3d4f47660a!2m2!1d2.168568!2d41.3873974!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Barcelona<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Perpiny%C3%A0,+Fran%C3%A7a\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@42.3385681,2.3089186,142900m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12b06e4e80fd88fd:0x1c83306520f2dd4f!2m2!1d2.8948332!2d42.6886591!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Perpi\u00f1\u00e1n<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Madrid\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.1693356,-2.7008932,582107m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0xd422997800a3c81:0xc436dec1618c2269!2m2!1d-3.7037902!2d40.4167754!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Madrid<\/a><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div class=%22uncode_text_column%22>\n<div class=%22flex_column av_one_third flex_column_div av-zero-column-padding avia-builder-el-22 el_after_av_one_third el_before_av_one_third column-top-margin%22>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<h6 style=%22text-align: left;%22><span style=%22color: #ff9900;%22>EN AVI\u00d3N<\/span><\/h6>\n<ul style=%22text-align: left;%22>\n<li><a href=%22https:\/\/www.girona-airport.net\/cat\/%22 class=%22cursor-init%22>Aeropuerto de Girona<\/a><\/li>\n<li><a href=%22https:\/\/www.aeropuertobarcelona-elprat.com\/%22 class=%22cursor-init%22>Aeropuerto de Barcelona<\/a><\/li>\n<\/ul>\n<h6 style=%22text-align: left;%22><span style=%22color: #ff9900;%22>EN TRANSPORTE P\u00daBLICO<\/span><\/h6>\n<p style=%22text-align: left;%22>Estaci\u00f3n de tren Adif Girona Costa Brava. Tren de alta velocidad con los principales destinos: Madrid, Zaragoza, Barcelona y la frontera con Francia. <span> <\/span><a href=%22https:\/\/www.renfe.com\/es\/es%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<p style=%22text-align: left;%22>Estaci\u00f3n de autobuses de Girona con m\u00faltiples destinos.<span> <\/span><a href=%22https:\/\/www.alsa.es\/ca\/estacions\/estacio-girona%22 class=%22cursor-init%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<p>\u00bb content_phone=\u00bb<\/p>\n<p data-start=%22136%22 data-end=%22157%22 style=%22text-align: center;%22><strong data-start=%22136%22 data-end=%22157%22>BIENVENIDO A GIRONA<\/strong><\/p>\n<p data-start=%22159%22 data-end=%22279%22 style=%22text-align: center;%22>En The Traka, solo tienes que pedalear. Todo tiene lugar en una misma zona, a solo cinco minutos del casco antiguo de Girona. <\/p>\n<p data-start=%22281%22 data-end=%22376%22 style=%22text-align: center;%22>\u00bfQuieres m\u00e1s? Descubre la historia, la gente, la gastronom\u00eda y las calles de la ciudad, a solo 100 km de Barcelona. <\/p>\n<p data-start=%22378%22 data-end=%22441%22 style=%22text-align: center;%22>El d\u00eda de la carrera, sal directamente desde tu casa, hotel o apartamento.<\/p>\n<p data-start=%22443%22 data-end=%22529%22 style=%22text-align: center;%22>Del <strong data-start=%22448%22 data-end=%22469%22>29 de abril al 3 de mayo<\/strong>, descubre por qu\u00e9 Girona es mucho m\u00e1s que la capital del ciclismo.<\/p>\n<p data-start=%22584%22 data-end=%22673%22 style=%22text-align: center;%22>\n<div class=%22text-lead%22>\n<p style=%22text-align: center;%22>\n<div class=%22uncode_text_column%22 style=%22text-align: center;%22>\n<h6 class=%22avia-image-overlay-wrap%22><span style=%22color: #ff9900;%22>EN COCHE<\/span><\/h6>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<ul>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Barcelona\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.690018,2.2086774,72182m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12a49816718e30e5:0x44b0fb3d4f47660a!2m2!1d2.168568!2d41.3873974!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Barcelona<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Perpiny%C3%A0,+Fran%C3%A7a\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@42.3385681,2.3089186,142900m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12b06e4e80fd88fd:0x1c83306520f2dd4f!2m2!1d2.8948332!2d42.6886591!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Perpi\u00f1\u00e1n<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Madrid\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.1693356,-2.7008932,582107m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0xd422997800a3c81:0xc436dec1618c2269!2m2!1d-3.7037902!2d40.4167754!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Madrid<\/a><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div class=%22uncode_text_column%22>\n<div class=%22flex_column av_one_third flex_column_div av-zero-column-padding avia-builder-el-22 el_after_av_one_third el_before_av_one_third column-top-margin%22>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<h6 style=%22text-align: center;%22><span style=%22color: #ff9900;%22>EN AVI\u00d3N<\/span><\/h6>\n<ul style=%22text-align: center;%22>\n<li><a href=%22https:\/\/www.girona-airport.net\/cat\/%22 class=%22cursor-init%22>Aeropuerto de Girona<\/a><\/li>\n<li><a href=%22https:\/\/www.aeropuertobarcelona-elprat.com\/%22 class=%22cursor-init%22>Aeropuerto de Barcelona<\/a><\/li>\n<\/ul>\n<h6 style=%22text-align: center;%22><span style=%22color: #ff9900;%22>EN TRANSPORTE P\u00daBLICO<\/span><\/h6>\n<p style=%22text-align: center;%22>Estaci\u00f3n de tren Adif Girona Costa Brava. Tren de alta velocidad con los principales destinos: Madrid, Zaragoza, Barcelona y la frontera con Francia. <span> <\/span><a href=%22https:\/\/www.renfe.com\/es\/es%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<p style=%22text-align: center;%22>Estaci\u00f3n de autobuses de Girona con m\u00faltiples destinos.<span> <\/span><a href=%22https:\/\/www.alsa.es\/ca\/estacions\/estacio-girona%22 class=%22cursor-init%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<p>\u00bb content_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><span>Parking 1: <a href=\"https:\/\/maps.app.goo.gl\/6XEMEfkJ56HS53hJ6\">https:\/\/maps.app.goo.gl\/6XEMEfkJ56HS53hJ6<\/a><\/span><\/p>\n<p><span>Parking 2: <a href=\"https:\/\/maps.app.goo.gl\/Vv44Gvm2Fx5JtFGN8\">https:\/\/maps.app.goo.gl\/Vv44Gvm2Fx5JtFGN8<\/a><\/span><\/p>\n<p><span>Zona de autocaravanas 1: <a href=\"https:\/\/maps.app.goo.gl\/AUtSkUAVehpVdczn9\">https:\/\/maps.app.goo.gl\/AUtSkUAVehpVdczn9<\/a><\/span><\/p>\n<p><span>Zona de autocaravanas 2 (Acceso de pago): <a href=\"https:\/\/maps.app.goo.gl\/nxR57Qkkkig59hXf8\">https:\/\/maps.app.goo.gl\/nxR57Qkkkig59hXf8<\/a><\/span><\/p>\n<p><span>Informaci\u00f3n y registro: <a href=\"https:\/\/maps.app.goo.gl\/T6ZWgiVmYg7ABZs47\">https:\/\/maps.app.goo.gl\/T6ZWgiVmYg7ABZs47<\/a><\/span><\/p>\n<p><span>Lavado de bicicletas: <a href=\"https:\/\/maps.app.goo.gl\/RyZiEtj92qxgGsh77\">https:\/\/maps.app.goo.gl\/RyZiEtj92qxgGsh77<\/a><\/span><\/p>\n<p><span>Punto m\u00e9dico: <a href=\"https:\/\/maps.app.goo.gl\/9T5mvmPbrBMk986V7\">https:\/\/maps.app.goo.gl\/9T5mvmPbrBMk986V7<\/a><\/span><\/p>\n<p><span>Zona de avituallamiento en la meta: <a href=\"https:\/\/maps.app.goo.gl\/15MyPeUBaS4QH4K48\">https:\/\/maps.app.goo.gl\/15MyPeUBaS4QH4K48<\/a><\/span><\/p>\n<p><span>Aseos port\u00e1tiles (todos los d\u00edas): <a href=\"https:\/\/maps.app.goo.gl\/PWWbp6NZ1fr3r2xw9\">https:\/\/maps.app.goo.gl\/PWWbp6NZ1fr3r2xw9<\/a><\/span><\/p>\n<p><span>Salida y llegada: <a href=\"https:\/\/maps.app.goo.gl\/nZYFyFw4utVa1xQr9\">https:\/\/maps.app.goo.gl\/nZYFyFw4utVa1xQr9<\/a><\/span><\/p>\n<p><span>Aseos y duchas (viernes): <a href=\"https:\/\/maps.app.goo.gl\/pScYagBE1zLKHGcU7\">https:\/\/maps.app.goo.gl\/pScYagBE1zLKHGcU7<\/a><\/span><\/p>\n<p><span>Duchas (s\u00e1bado y domingo): <a href=\"https:\/\/maps.app.goo.gl\/emcb93Lrftqe1kb16\">https:\/\/maps.app.goo.gl\/emcb93Lrftqe1kb16<\/a><\/span><\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbESPECIFICACIONES DEL APARCAMIENTO\u00bb title_last_edited=\u00bboff|phone\u00bb content_tablet=\u00bb<\/p>\n<p data-start=%22136%22 data-end=%22157%22 style=%22text-align: left;%22><strong data-start=%22136%22 data-end=%22157%22>BIENVENIDO A GIRONA<\/strong><\/p>\n<p data-start=%22159%22 data-end=%22279%22 style=%22text-align: left;%22>En The Traka, solo tienes que pedalear. Todo tiene lugar en una misma zona, a solo cinco minutos del casco antiguo de Girona. <\/p>\n<p data-start=%22281%22 data-end=%22376%22 style=%22text-align: left;%22>\u00bfQuieres m\u00e1s? Descubre la historia, la gente, la gastronom\u00eda y las calles de la ciudad, a solo 100 km de Barcelona. <\/p>\n<p data-start=%22378%22 data-end=%22441%22 style=%22text-align: left;%22>El d\u00eda de la carrera, sal directamente desde tu casa, hotel o apartamento.<\/p>\n<p data-start=%22443%22 data-end=%22529%22 style=%22text-align: left;%22>Del <strong data-start=%22448%22 data-end=%22469%22>29 de abril al 3 de mayo<\/strong>, descubre por qu\u00e9 Girona es mucho m\u00e1s que la capital del ciclismo.<\/p>\n<p data-start=%22584%22 data-end=%22673%22 style=%22text-align: left;%22>\n<div class=%22text-lead%22>\n<p style=%22text-align: left;%22>\n<div class=%22uncode_text_column%22 style=%22text-align: left;%22>\n<h6 class=%22avia-image-overlay-wrap%22><span style=%22color: #ff9900;%22>EN COCHE<\/span><\/h6>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<ul>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Barcelona\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.690018,2.2086774,72182m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12a49816718e30e5:0x44b0fb3d4f47660a!2m2!1d2.168568!2d41.3873974!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Barcelona<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Perpiny%C3%A0,+Fran%C3%A7a\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@42.3385681,2.3089186,142900m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12b06e4e80fd88fd:0x1c83306520f2dd4f!2m2!1d2.8948332!2d42.6886591!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Perpi\u00f1\u00e1n<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Madrid\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.1693356,-2.7008932,582107m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0xd422997800a3c81:0xc436dec1618c2269!2m2!1d-3.7037902!2d40.4167754!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Madrid<\/a><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div class=%22uncode_text_column%22>\n<div class=%22flex_column av_one_third flex_column_div av-zero-column-padding avia-builder-el-22 el_after_av_one_third el_before_av_one_third column-top-margin%22>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<h6 style=%22text-align: left;%22><span style=%22color: #ff9900;%22>EN AVI\u00d3N<\/span><\/h6>\n<ul style=%22text-align: left;%22>\n<li><a href=%22https:\/\/www.girona-airport.net\/cat\/%22 class=%22cursor-init%22>Aeropuerto de Girona<\/a><\/li>\n<li><a href=%22https:\/\/www.aeropuertobarcelona-elprat.com\/%22 class=%22cursor-init%22>Aeropuerto de Barcelona<\/a><\/li>\n<\/ul>\n<h6 style=%22text-align: left;%22><span style=%22color: #ff9900;%22>EN TRANSPORTE P\u00daBLICO<\/span><\/h6>\n<p style=%22text-align: left;%22>Estaci\u00f3n de tren Adif Girona Costa Brava. Tren de alta velocidad con los principales destinos: Madrid, Zaragoza, Barcelona y la frontera con Francia. <span> <\/span><a href=%22https:\/\/www.renfe.com\/es\/es%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<p style=%22text-align: left;%22>Estaci\u00f3n de autobuses de Girona con m\u00faltiples destinos.<span> <\/span><a href=%22https:\/\/www.alsa.es\/ca\/estacions\/estacio-girona%22 class=%22cursor-init%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<p>\u00bb content_phone=\u00bb<\/p>\n<p data-start=%22136%22 data-end=%22157%22 style=%22text-align: center;%22><strong data-start=%22136%22 data-end=%22157%22>BIENVENIDO A GIRONA<\/strong><\/p>\n<p data-start=%22159%22 data-end=%22279%22 style=%22text-align: center;%22>En The Traka, solo tienes que pedalear. Todo tiene lugar en una misma zona, a solo cinco minutos del casco antiguo de Girona. <\/p>\n<p data-start=%22281%22 data-end=%22376%22 style=%22text-align: center;%22>\u00bfQuieres m\u00e1s? Descubre la historia, la gente, la gastronom\u00eda y las calles de la ciudad, a solo 100 km de Barcelona. <\/p>\n<p data-start=%22378%22 data-end=%22441%22 style=%22text-align: center;%22>El d\u00eda de la carrera, sal directamente desde tu casa, hotel o apartamento.<\/p>\n<p data-start=%22443%22 data-end=%22529%22 style=%22text-align: center;%22>Del <strong data-start=%22448%22 data-end=%22469%22>29 de abril al 3 de mayo<\/strong>, descubre por qu\u00e9 Girona es mucho m\u00e1s que la capital del ciclismo.<\/p>\n<p data-start=%22584%22 data-end=%22673%22 style=%22text-align: center;%22>\n<div class=%22text-lead%22>\n<p style=%22text-align: center;%22>\n<div class=%22uncode_text_column%22 style=%22text-align: center;%22>\n<h6 class=%22avia-image-overlay-wrap%22><span style=%22color: #ff9900;%22>EN COCHE<\/span><\/h6>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<ul>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Barcelona\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.690018,2.2086774,72182m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12a49816718e30e5:0x44b0fb3d4f47660a!2m2!1d2.168568!2d41.3873974!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Barcelona<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Perpiny%C3%A0,+Fran%C3%A7a\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@42.3385681,2.3089186,142900m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12b06e4e80fd88fd:0x1c83306520f2dd4f!2m2!1d2.8948332!2d42.6886591!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Perpi\u00f1\u00e1n<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Madrid\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.1693356,-2.7008932,582107m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0xd422997800a3c81:0xc436dec1618c2269!2m2!1d-3.7037902!2d40.4167754!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Madrid<\/a><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div class=%22uncode_text_column%22>\n<div class=%22flex_column av_one_third flex_column_div av-zero-column-padding avia-builder-el-22 el_after_av_one_third el_before_av_one_third column-top-margin%22>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<h6 style=%22text-align: center;%22><span style=%22color: #ff9900;%22>EN AVI\u00d3N<\/span><\/h6>\n<ul style=%22text-align: center;%22>\n<li><a href=%22https:\/\/www.girona-airport.net\/cat\/%22 class=%22cursor-init%22>Aeropuerto de Girona<\/a><\/li>\n<li><a href=%22https:\/\/www.aeropuertobarcelona-elprat.com\/%22 class=%22cursor-init%22>Aeropuerto de Barcelona<\/a><\/li>\n<\/ul>\n<h6 style=%22text-align: center;%22><span style=%22color: #ff9900;%22>EN TRANSPORTE P\u00daBLICO<\/span><\/h6>\n<p style=%22text-align: center;%22>Estaci\u00f3n de tren Adif Girona Costa Brava. Tren de alta velocidad con los principales destinos: Madrid, Zaragoza, Barcelona y la frontera con Francia. <span> <\/span><a href=%22https:\/\/www.renfe.com\/es\/es%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<p style=%22text-align: center;%22>Estaci\u00f3n de autobuses de Girona con m\u00faltiples destinos.<span> <\/span><a href=%22https:\/\/www.alsa.es\/ca\/estacions\/estacio-girona%22 class=%22cursor-init%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<p>\u00bb content_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>\u2022 APARCAMIENTO 1: <\/span><a href=\"https:\/\/maps.app.goo.gl\/kS2m6E9TTrbbRHRJA\"><span>https:\/\/maps.app.goo.gl\/kS2m6E9TTrbbRHRJA<\/span><\/a><br \/><span>\u2022 APARCAMIENTO 2: <\/span><a href=\"https:\/\/maps.app.goo.gl\/U8McTrRa4w7N9oui9\"><span>https:\/\/maps.app.goo.gl\/U8McTrRa4w7N9oui9<\/span><\/a><br \/><span>\u2022 APARCAMIENTO 3: <\/span><a href=\"https:\/\/maps.app.goo.gl\/JAirEiJb7ycHbdsVA\"><span>https:\/\/maps.app.goo.gl\/JAirEiJb7ycHbdsVA<\/span><\/a><\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbASISTENCIA M\u00c9DICA\u00bb title_last_edited=\u00bboff|phone\u00bb content_tablet=\u00bb<\/p>\n<p data-start=%22136%22 data-end=%22157%22 style=%22text-align: left;%22><strong data-start=%22136%22 data-end=%22157%22>BIENVENIDO A GIRONA<\/strong><\/p>\n<p data-start=%22159%22 data-end=%22279%22 style=%22text-align: left;%22>En The Traka, solo tienes que pedalear. Todo tiene lugar en una misma zona, a solo cinco minutos del casco antiguo de Girona. <\/p>\n<p data-start=%22281%22 data-end=%22376%22 style=%22text-align: left;%22>\u00bfQuieres m\u00e1s? Descubre la historia, la gente, la gastronom\u00eda y las calles de la ciudad, a solo 100 km de Barcelona. <\/p>\n<p data-start=%22378%22 data-end=%22441%22 style=%22text-align: left;%22>El d\u00eda de la carrera, sal directamente desde tu casa, hotel o apartamento.<\/p>\n<p data-start=%22443%22 data-end=%22529%22 style=%22text-align: left;%22>Del <strong data-start=%22448%22 data-end=%22469%22>29 de abril al 3 de mayo<\/strong>, descubre por qu\u00e9 Girona es mucho m\u00e1s que la capital del ciclismo.<\/p>\n<p data-start=%22584%22 data-end=%22673%22 style=%22text-align: left;%22>\n<div class=%22text-lead%22>\n<p style=%22text-align: left;%22>\n<div class=%22uncode_text_column%22 style=%22text-align: left;%22>\n<h6 class=%22avia-image-overlay-wrap%22><span style=%22color: #ff9900;%22>EN COCHE<\/span><\/h6>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<ul>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Barcelona\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.690018,2.2086774,72182m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12a49816718e30e5:0x44b0fb3d4f47660a!2m2!1d2.168568!2d41.3873974!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Barcelona<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Perpiny%C3%A0,+Fran%C3%A7a\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@42.3385681,2.3089186,142900m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12b06e4e80fd88fd:0x1c83306520f2dd4f!2m2!1d2.8948332!2d42.6886591!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Perpi\u00f1\u00e1n<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Madrid\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.1693356,-2.7008932,582107m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0xd422997800a3c81:0xc436dec1618c2269!2m2!1d-3.7037902!2d40.4167754!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Madrid<\/a><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div class=%22uncode_text_column%22>\n<div class=%22flex_column av_one_third flex_column_div av-zero-column-padding avia-builder-el-22 el_after_av_one_third el_before_av_one_third column-top-margin%22>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<h6 style=%22text-align: left;%22><span style=%22color: #ff9900;%22>EN AVI\u00d3N<\/span><\/h6>\n<ul style=%22text-align: left;%22>\n<li><a href=%22https:\/\/www.girona-airport.net\/cat\/%22 class=%22cursor-init%22>Aeropuerto de Girona<\/a><\/li>\n<li><a href=%22https:\/\/www.aeropuertobarcelona-elprat.com\/%22 class=%22cursor-init%22>Aeropuerto de Barcelona<\/a><\/li>\n<\/ul>\n<h6 style=%22text-align: left;%22><span style=%22color: #ff9900;%22>EN TRANSPORTE P\u00daBLICO<\/span><\/h6>\n<p style=%22text-align: left;%22>Estaci\u00f3n de tren Adif Girona Costa Brava. Tren de alta velocidad con los principales destinos: Madrid, Zaragoza, Barcelona y la frontera con Francia. <span> <\/span><a href=%22https:\/\/www.renfe.com\/es\/es%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<p style=%22text-align: left;%22>Estaci\u00f3n de autobuses de Girona con m\u00faltiples destinos.<span> <\/span><a href=%22https:\/\/www.alsa.es\/ca\/estacions\/estacio-girona%22 class=%22cursor-init%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<p>\u00bb content_phone=\u00bb<\/p>\n<p data-start=%22136%22 data-end=%22157%22 style=%22text-align: center;%22><strong data-start=%22136%22 data-end=%22157%22>BIENVENIDO A GIRONA<\/strong><\/p>\n<p data-start=%22159%22 data-end=%22279%22 style=%22text-align: center;%22>En The Traka, solo tienes que pedalear. Todo tiene lugar en una misma zona, a solo cinco minutos del casco antiguo de Girona. <\/p>\n<p data-start=%22281%22 data-end=%22376%22 style=%22text-align: center;%22>\u00bfQuieres m\u00e1s? Descubre la historia, la gente, la gastronom\u00eda y las calles de la ciudad, a solo 100 km de Barcelona. <\/p>\n<p data-start=%22378%22 data-end=%22441%22 style=%22text-align: center;%22>El d\u00eda de la carrera, sal directamente desde tu casa, hotel o apartamento.<\/p>\n<p data-start=%22443%22 data-end=%22529%22 style=%22text-align: center;%22>Del <strong data-start=%22448%22 data-end=%22469%22>29 de abril al 3 de mayo<\/strong>, descubre por qu\u00e9 Girona es mucho m\u00e1s que la capital del ciclismo.<\/p>\n<p data-start=%22584%22 data-end=%22673%22 style=%22text-align: center;%22>\n<div class=%22text-lead%22>\n<p style=%22text-align: center;%22>\n<div class=%22uncode_text_column%22 style=%22text-align: center;%22>\n<h6 class=%22avia-image-overlay-wrap%22><span style=%22color: #ff9900;%22>EN COCHE<\/span><\/h6>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<ul>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Barcelona\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.690018,2.2086774,72182m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12a49816718e30e5:0x44b0fb3d4f47660a!2m2!1d2.168568!2d41.3873974!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Barcelona<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Perpiny%C3%A0,+Fran%C3%A7a\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@42.3385681,2.3089186,142900m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0x12b06e4e80fd88fd:0x1c83306520f2dd4f!2m2!1d2.8948332!2d42.6886591!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Perpi\u00f1\u00e1n<\/a><\/li>\n<li><a href=%22https:\/\/www.google.com\/maps\/dir\/Madrid\/Pavell%C3%B3+Municipal+Girona+-+Fontajau,+Avinguda+del+President+Josep+Tarradellas+i+Joan,+22,+24,+17007+Girona\/@41.1693356,-2.7008932,582107m\/data=!3m2!1e3!4b1!4m14!4m13!1m5!1m1!1s0xd422997800a3c81:0xc436dec1618c2269!2m2!1d-3.7037902!2d40.4167754!1m5!1m1!1s0x12bae71bcf31ab13:0xee3043f110a08a72!2m2!1d2.8110463!2d41.9906513!3e0%22 class=%22cursor-init%22>Desde Madrid<\/a><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div class=%22uncode_text_column%22>\n<div class=%22flex_column av_one_third flex_column_div av-zero-column-padding avia-builder-el-22 el_after_av_one_third el_before_av_one_third column-top-margin%22>\n<section class=%22av_textblock_section %22>\n<div class=%22avia_textblock %22>\n<h6 style=%22text-align: center;%22><span style=%22color: #ff9900;%22>EN AVI\u00d3N<\/span><\/h6>\n<ul style=%22text-align: center;%22>\n<li><a href=%22https:\/\/www.girona-airport.net\/cat\/%22 class=%22cursor-init%22>Aeropuerto de Girona<\/a><\/li>\n<li><a href=%22https:\/\/www.aeropuertobarcelona-elprat.com\/%22 class=%22cursor-init%22>Aeropuerto de Barcelona<\/a><\/li>\n<\/ul>\n<h6 style=%22text-align: center;%22><span style=%22color: #ff9900;%22>EN TRANSPORTE P\u00daBLICO<\/span><\/h6>\n<p style=%22text-align: center;%22>Estaci\u00f3n de tren Adif Girona Costa Brava. Tren de alta velocidad con los principales destinos: Madrid, Zaragoza, Barcelona y la frontera con Francia. <span> <\/span><a href=%22https:\/\/www.renfe.com\/es\/es%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<p style=%22text-align: center;%22>Estaci\u00f3n de autobuses de Girona con m\u00faltiples destinos.<span> <\/span><a href=%22https:\/\/www.alsa.es\/ca\/estacions\/estacio-girona%22 class=%22cursor-init%22>*M\u00e1s informaci\u00f3n<\/a><\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<p>\u00bb content_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p class=\"isSelectedEnd\"><span>Tanto el seguro m\u00e9dico propio del participante como el seguro contratado a trav\u00e9s de la organizaci\u00f3n son privados.<\/span><br \/><strong><span>NO HAY COBERTURA PARA LA ATENCI\u00d3N M\u00c9DICA EN CENTROS SANITARIOS P\u00daBLICOS.<\/span><\/strong><\/p>\n<p class=\"isSelectedEnd\"><span>Para cualquier asistencia m\u00e9dica necesaria durante el evento, los participantes cubiertos por el seguro contratado a trav\u00e9s de la organizaci\u00f3n deber\u00e1n acudir a los siguientes centros de referencia:<\/span><\/p>\n<p class=\"isSelectedEnd\"><strong><span>GIRONA:<\/span><\/strong><br \/><a href=\"https:\/\/share.google\/VVz4JDWDViYo7LaiD\"><span>CL\u00cdNIC ONYAR, CAUSSE CLINIC<\/span><\/a><br \/><span>Hero\u00efnes de Sta. B\u00e0rbara, 6<\/span><br \/><span>Tel. +34 972 204 900 \/ +34 972 222 644<\/span><\/p>\n<p class=\"isSelectedEnd\"><a href=\"https:\/\/share.google\/ufMb69Tg8g7WW29eX\"><span>CL\u00cdNICA BOFILL CENTRAL<\/span><\/a><br \/><span>Rnda. Sant Antoni M. Claret, 20<\/span><br \/><span>Tel. +34 972 410 404 \/ +34 972 204 350<\/span><\/p>\n<p class=\"isSelectedEnd\"><strong><span>FIGUERES<\/span><\/strong><span> <\/span><em><span>(especialmente para los participantes de la ruta 360, si es necesario)<\/span><\/em><br \/><a href=\"https:\/\/share.google\/4XQS4g3whFtLOcGJn\"><span>CL\u00cdNICA SANTA CREU<\/span><\/a><br \/><span>Pere III, 41<\/span><br \/><span>Tel. +34 972 503 650 \/ +34 972 501 750<\/span><\/p>\n<p><a href=\"https:\/\/share.google\/bLucDdnXpNsDkS5hS\"><span>HOSPITAL DE FIGUERES<\/span><\/a><br \/><span>Ronda Dr. Arolas, s\/n<\/span><br \/><span>Tel. +34 972 501 400<\/span><\/p>\n<h3><span>CONDICIONES DE ASISTENCIA<\/span><\/h3>\n<p class=\"isSelectedEnd\"><span>La asistencia m\u00e9dica cubierta por el seguro contratado a trav\u00e9s de la organizaci\u00f3n se presta exclusivamente en los centros indicados.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>La atenci\u00f3n m\u00e9dica recibida en otros centros, as\u00ed como identificarse como participante de THE TRAKA fuera de esta red, puede generar costes que <\/span><strong><span>en ning\u00fan caso ser\u00e1n asumidos por la organizaci\u00f3n<\/span><\/strong><span>, y ser\u00e1n responsabilidad exclusiva del participante.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Si el participante tiene su propio seguro m\u00e9dico privado, debe verificar previamente qu\u00e9 centros est\u00e1n cubiertos por su p\u00f3liza y acudir directamente a esos centros.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Cualquier asistencia m\u00e9dica requerida una vez finalizado el evento no est\u00e1 cubierta por la organizaci\u00f3n.<\/span><\/p>\n<p><span>La organizaci\u00f3n declina expresamente cualquier responsabilidad por gastos, cargos o reclamaciones derivados de la atenci\u00f3n m\u00e9dica recibida en centros no incluidos en la red indicada y\/o en centros sanitarios p\u00fablicos, ya que dicha atenci\u00f3n no est\u00e1 cubierta por estas condiciones.<\/span><\/p>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UBICACIONESParking 1: https:\/\/maps.app.goo.gl\/6XEMEfkJ56HS53hJ6 Parking 2: https:\/\/maps.app.goo.gl\/Vv44Gvm2Fx5JtFGN8 Zona de autocaravanas 1: https:\/\/maps.app.goo.gl\/AUtSkUAVehpVdczn9 Zona de autocaravanas 2 (Acceso de pago): https:\/\/maps.app.goo.gl\/nxR57Qkkkig59hXf8 Informaci\u00f3n y registro: https:\/\/maps.app.goo.gl\/T6ZWgiVmYg7ABZs47 Lavado de bicicletas: https:\/\/maps.app.goo.gl\/RyZiEtj92qxgGsh77 Punto m\u00e9dico: https:\/\/maps.app.goo.gl\/9T5mvmPbrBMk986V7 Zona de avituallamiento en la meta: https:\/\/maps.app.goo.gl\/15MyPeUBaS4QH4K48 Aseos port\u00e1tiles (todos los d\u00edas): https:\/\/maps.app.goo.gl\/PWWbp6NZ1fr3r2xw9 Salida y llegada: https:\/\/maps.app.goo.gl\/nZYFyFw4utVa1xQr9 Aseos y duchas (viernes): https:\/\/maps.app.goo.gl\/pScYagBE1zLKHGcU7 Duchas (s\u00e1bado y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":550,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-726","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":32,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages\/726\/revisions"}],"predecessor-version":[{"id":7150,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/pages\/726\/revisions\/7150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/media\/550"}],"wp:attachment":[{"href":"https:\/\/www.thetraka.com\/es\/wp-json\/wp\/v2\/media?parent=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}